{"id":83727,"date":"2021-08-03T10:42:32","date_gmt":"2021-08-03T14:42:32","guid":{"rendered":"https:\/\/www.foliot.com\/decouvrez-gouvernement\/desks\/"},"modified":"2021-08-03T15:54:38","modified_gmt":"2021-08-03T19:54:38","slug":"pupitres","status":"publish","type":"page","link":"https:\/\/www.foliot.com\/fr\/decouvrez-gouvernement\/pupitres\/","title":{"rendered":"Pupitres"},"content":{"rendered":"\n<p class=\"has-text-align-center is-style-intro has-large-font-size\">Modernes ou traditionnels, les pupitres Foliot sont polyvalents et robustes pour assurer leur dur\u00e9e de vie dans un environnement institutionnel et dynamique.<\/p>\n\n\n\n<section class=\"products__listing alignwide\">\n  <div id=\"filter-bar\" class=\"products__grid__filter\">\n  <div class=\"items__count\">\n          \n      <div class=\"facetwp-facet facetwp-facet-facetwp_product_count facetwp-type-pager\" data-name=\"facetwp_product_count\" data-type=\"pager\"><\/div>     \n     \n  <\/div>\n    \n        \n<div class=\"facet-filters__inline\">\n  <div class=\"facetwp-selections\"><\/div><\/div>\n\n        \n<div class=\"filter-actions\">\n    <button class=\"filter-toggle\" aria-expanded=\"false\" aria-label=\"Ouvrir le panneau de filtres\"><span class=\"filter-toggle__label\">Filtres<\/span><i class=\"icomoon-filters\"><\/i><\/button>\n<\/div>\n<div id=\"filter-pannel\" class=\"filter-pannel\">\n<button class=\"filter-reset btn--primary btn--small\" onclick=\"FWP.reset()\">Effacer les filtres<\/button>\n  \n    <button class=\"filter-pannel__close\"><\/button>\n    <div class=\"filter-pannel__inner\">\n \n            <div class=\"filter-pannel__accordeon filter-pannel__accordeon--product_type\" aria-expanded=\"false\">\n    \n      <button class=\"filter-pannel__accordeon__header\"  aria-label=\"\n        Ouvrir l&#039;accord\u00e9on Type         \">\n          <div class=\"filter-pannel__accordeon__title\">Type<\/div>\n          <div class=\"filter-pannel__accordeon__toggle\" >\n            <div class=\"btn-inner\">\n              <i class=\"down-arrow\"><\/i>\n            <\/div>\n          <\/div>\n        <\/button>\n        <div class=\"filter-pannel__accordeon__content\">\n          <div class=\"facetwp-facet facetwp-facet-fwp_product_types facetwp-type-checkboxes\" data-name=\"fwp_product_types\" data-type=\"checkboxes\"><\/div>        <\/div>\n      <\/div>\n            <div class=\"filter-pannel__accordeon filter-pannel__accordeon--collections\" aria-expanded=\"false\">\n    \n      <button class=\"filter-pannel__accordeon__header\"  aria-label=\"\n        Ouvrir l&#039;accord\u00e9on Marque \/ Collection         \">\n          <div class=\"filter-pannel__accordeon__title\">Marque \/ Collection<\/div>\n          <div class=\"filter-pannel__accordeon__toggle\" >\n            <div class=\"btn-inner\">\n              <i class=\"down-arrow\"><\/i>\n            <\/div>\n          <\/div>\n        <\/button>\n        <div class=\"filter-pannel__accordeon__content\">\n          <div class=\"facetwp-facet facetwp-facet-facetwp_product_collections facetwp-type-checkboxes\" data-name=\"facetwp_product_collections\" data-type=\"checkboxes\"><\/div>        <\/div>\n      <\/div>\n         \n    <\/div>\n  <\/div>\n     \n<\/div>\n<div class=\"products__grid facetwp-template\">\n\n          \n      \n<a href=\"https:\/\/www.foliot.com\/fr\/produits\/bureau-1-tiroir-section-ouverte-dgnds-101s\/\" class=\"product__item\" data-product=\"{&quot;types&quot;:&quot;&quot;,&quot;rating&quot;:&quot;-&quot;,&quot;description&quot;:&quot;&quot;,&quot;dimensions&quot;:{&quot;in&quot;:{&quot;depth&quot;:&quot;24.00&quot;,&quot;height&quot;:&quot;30.00&quot;,&quot;width&quot;:&quot;42.00&quot;},&quot;cm&quot;:{&quot;depth&quot;:61,&quot;height&quot;:76,&quot;width&quot;:107}},&quot;image&quot;:&quot;https:\\\/\\\/www.foliot.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FG_DGNDS-101S-1.jpg&quot;,&quot;code&quot;:&quot;DGNDS-101S&quot;,&quot;id&quot;:44598}\" >\n  <div class=\"product__image\">\n    <div class=\"product__actions\">\n     <div id=\"compare-actions-DGNDS-101S\" class=\"product__actions__compare\">\n    <\/div>\n    <\/div>\n\n      <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/02\/FG_DGNDS-101S-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>  \n      <div class=\"product__image__hover\">\n    <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/02\/FG_DGNDS-101S-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>    <\/div>\n    \n\n  <\/div>\n  <div class=\"product__desc\">\n    <div class=\"product__desc__top\">\n      <div class=\"product__desc__top__left\">\n                          <p class=\"product__name\">Bureau 1 Tiroir et Section Ouverte<\/p>\n                          <p class=\"product__code\">DGNDS-101S<\/p>\n              <\/div>\n      <div class=\"product__desc__top__right\">\n                \n  <button class=\"add-to__btn add-to__btn--wishlist add-to-wishlist-btn product\"\n    data-item_id=\"44598\"\n    data-item_name=\"Bureau 1 Tiroir et Section Ouverte\"\n    data-type=\"product\"\n    title=\"Ajouter aux favoris\"\n    id=\"wish-44598\">\n    \n  <i class=\"icon add-to-wishlist product\"><\/i>\n\n  <span class=\"sr-only\">\n    Ajouter Bureau 1 Tiroir et Section Ouverte-DGNDS-101S \u00e0 mes favoris  <\/span>\n  <\/button>\n\n      <\/div>\n    <\/div>\n    <div class=\"product__desc__bottom\">\n          <p class=\"product__manufacturer\">44132<\/p>\n        <\/div>\n\n  <\/div>\n<\/a>\n        \n      \n<a href=\"https:\/\/www.foliot.com\/fr\/produits\/table-de-travail-aria-avec-pattes-en-metal-dards-001s\/\" class=\"product__item\" data-product=\"{&quot;types&quot;:&quot;&quot;,&quot;rating&quot;:&quot;-&quot;,&quot;description&quot;:&quot;&quot;,&quot;dimensions&quot;:{&quot;in&quot;:{&quot;depth&quot;:&quot;24.00&quot;,&quot;height&quot;:&quot;30.00&quot;,&quot;width&quot;:&quot;30.00&quot;},&quot;cm&quot;:{&quot;depth&quot;:61,&quot;height&quot;:76,&quot;width&quot;:76}},&quot;image&quot;:&quot;https:\\\/\\\/www.foliot.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/FG_DARDS-001S_Front-2.jpg&quot;,&quot;code&quot;:&quot;DARDS-001S&quot;,&quot;id&quot;:44620}\" >\n  <div class=\"product__image\">\n    <div class=\"product__actions\">\n     <div id=\"compare-actions-DARDS-001S\" class=\"product__actions__compare\">\n    <\/div>\n    <\/div>\n\n      <img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/03\/FG_DARDS-001S_Front-2.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>  \n      <div class=\"product__image__hover\">\n    <img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/05\/FG_DARDS-001S.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>    <\/div>\n    \n\n  <\/div>\n  <div class=\"product__desc\">\n    <div class=\"product__desc__top\">\n      <div class=\"product__desc__top__left\">\n                          <p class=\"product__name\">Pupitre Aria Avec Pattes En M\u00e9tal<\/p>\n                          <p class=\"product__code\">DARDS-001S<\/p>\n              <\/div>\n      <div class=\"product__desc__top__right\">\n                \n  <button class=\"add-to__btn add-to__btn--wishlist add-to-wishlist-btn product\"\n    data-item_id=\"44620\"\n    data-item_name=\"Pupitre Aria Avec Pattes En M\u00e9tal\"\n    data-type=\"product\"\n    title=\"Ajouter aux favoris\"\n    id=\"wish-44620\">\n    \n  <i class=\"icon add-to-wishlist product\"><\/i>\n\n  <span class=\"sr-only\">\n    Ajouter Pupitre Aria Avec Pattes En M\u00e9tal-DARDS-001S \u00e0 mes favoris  <\/span>\n  <\/button>\n\n      <\/div>\n    <\/div>\n    <div class=\"product__desc__bottom\">\n          <p class=\"product__manufacturer\">44132<\/p>\n        <\/div>\n\n  <\/div>\n<\/a>\n        \n      \n<a href=\"https:\/\/www.foliot.com\/fr\/produits\/bureau-2-tiroirs-1-classeur-dgnds-302s\/\" class=\"product__item\" data-product=\"{&quot;types&quot;:&quot;&quot;,&quot;rating&quot;:&quot;-&quot;,&quot;description&quot;:&quot;&quot;,&quot;dimensions&quot;:{&quot;in&quot;:{&quot;depth&quot;:&quot;24.00&quot;,&quot;height&quot;:&quot;30.00&quot;,&quot;width&quot;:&quot;42.00&quot;},&quot;cm&quot;:{&quot;depth&quot;:61,&quot;height&quot;:76,&quot;width&quot;:107}},&quot;image&quot;:&quot;https:\\\/\\\/www.foliot.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FG_DGNDS-302S-1.jpg&quot;,&quot;code&quot;:&quot;DGNDS-302S&quot;,&quot;id&quot;:44548}\" >\n  <div class=\"product__image\">\n    <div class=\"product__actions\">\n     <div id=\"compare-actions-DGNDS-302S\" class=\"product__actions__compare\">\n    <\/div>\n    <\/div>\n\n      <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/02\/FG_DGNDS-302S-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>  \n      <div class=\"product__image__hover\">\n    <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/02\/FG_DGNDS-302S-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>    <\/div>\n    \n\n  <\/div>\n  <div class=\"product__desc\">\n    <div class=\"product__desc__top\">\n      <div class=\"product__desc__top__left\">\n                          <p class=\"product__name\">Pupitre 2 Tiroirs et 1 Classeur<\/p>\n                          <p class=\"product__code\">DGNDS-302S<\/p>\n              <\/div>\n      <div class=\"product__desc__top__right\">\n                \n  <button class=\"add-to__btn add-to__btn--wishlist add-to-wishlist-btn product\"\n    data-item_id=\"44548\"\n    data-item_name=\"Pupitre 2 Tiroirs et 1 Classeur\"\n    data-type=\"product\"\n    title=\"Ajouter aux favoris\"\n    id=\"wish-44548\">\n    \n  <i class=\"icon add-to-wishlist product\"><\/i>\n\n  <span class=\"sr-only\">\n    Ajouter Pupitre 2 Tiroirs et 1 Classeur-DGNDS-302S \u00e0 mes favoris  <\/span>\n  <\/button>\n\n      <\/div>\n    <\/div>\n    <div class=\"product__desc__bottom\">\n          <p class=\"product__manufacturer\">44132<\/p>\n        <\/div>\n\n  <\/div>\n<\/a>\n        \n      \n<a href=\"https:\/\/www.foliot.com\/fr\/produits\/surface-de-travail-dgnds-108s\/\" class=\"product__item\" data-product=\"{&quot;types&quot;:&quot;&quot;,&quot;rating&quot;:&quot;-&quot;,&quot;description&quot;:&quot;&quot;,&quot;dimensions&quot;:{&quot;in&quot;:{&quot;depth&quot;:&quot;36.00&quot;,&quot;height&quot;:&quot;36.00&quot;,&quot;width&quot;:&quot;76.00&quot;},&quot;cm&quot;:{&quot;depth&quot;:91,&quot;height&quot;:91,&quot;width&quot;:193}},&quot;image&quot;:&quot;https:\\\/\\\/www.foliot.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/FG_DGNDS-108S_Front-1.jpg&quot;,&quot;code&quot;:&quot;DGNDS-108S&quot;,&quot;id&quot;:44552}\" >\n  <div class=\"product__image\">\n    <div class=\"product__actions\">\n     <div id=\"compare-actions-DGNDS-108S\" class=\"product__actions__compare\">\n    <\/div>\n    <\/div>\n\n      <img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/05\/FG_DGNDS-108S_Front-1.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>  \n      <div class=\"product__image__hover\">\n    <img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/05\/FG_DGNDS-108S.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>    <\/div>\n    \n\n  <\/div>\n  <div class=\"product__desc\">\n    <div class=\"product__desc__top\">\n      <div class=\"product__desc__top__left\">\n                          <p class=\"product__name\">Surface De Travail<\/p>\n                          <p class=\"product__code\">DGNDS-108S<\/p>\n              <\/div>\n      <div class=\"product__desc__top__right\">\n                \n  <button class=\"add-to__btn add-to__btn--wishlist add-to-wishlist-btn product\"\n    data-item_id=\"44552\"\n    data-item_name=\"Surface De Travail\"\n    data-type=\"product\"\n    title=\"Ajouter aux favoris\"\n    id=\"wish-44552\">\n    \n  <i class=\"icon add-to-wishlist product\"><\/i>\n\n  <span class=\"sr-only\">\n    Ajouter Surface De Travail-DGNDS-108S \u00e0 mes favoris  <\/span>\n  <\/button>\n\n      <\/div>\n    <\/div>\n    <div class=\"product__desc__bottom\">\n          <p class=\"product__manufacturer\">44132<\/p>\n        <\/div>\n\n  <\/div>\n<\/a>\n        \n      \n<a href=\"https:\/\/www.foliot.com\/fr\/produits\/bureau-3-tiroirs-dgnds-301s\/\" class=\"product__item\" data-product=\"{&quot;types&quot;:&quot;&quot;,&quot;rating&quot;:&quot;-&quot;,&quot;description&quot;:&quot;&quot;,&quot;dimensions&quot;:{&quot;in&quot;:{&quot;depth&quot;:&quot;27.00&quot;,&quot;height&quot;:&quot;30.00&quot;,&quot;width&quot;:&quot;42.00&quot;},&quot;cm&quot;:{&quot;depth&quot;:69,&quot;height&quot;:76,&quot;width&quot;:107}},&quot;image&quot;:&quot;https:\\\/\\\/www.foliot.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FG_DGNDS-301S-1.jpg&quot;,&quot;code&quot;:&quot;DGNDS-301S&quot;,&quot;id&quot;:44612}\" >\n  <div class=\"product__image\">\n    <div class=\"product__actions\">\n     <div id=\"compare-actions-DGNDS-301S\" class=\"product__actions__compare\">\n    <\/div>\n    <\/div>\n\n      <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/02\/FG_DGNDS-301S-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>  \n      <div class=\"product__image__hover\">\n    <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2021\/02\/FG_DGNDS-301S-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>    <\/div>\n    \n\n  <\/div>\n  <div class=\"product__desc\">\n    <div class=\"product__desc__top\">\n      <div class=\"product__desc__top__left\">\n                          <p class=\"product__name\">Pupitre 3 Tiroirs<\/p>\n                          <p class=\"product__code\">DGNDS-301S<\/p>\n              <\/div>\n      <div class=\"product__desc__top__right\">\n                \n  <button class=\"add-to__btn add-to__btn--wishlist add-to-wishlist-btn product\"\n    data-item_id=\"44612\"\n    data-item_name=\"Pupitre 3 Tiroirs\"\n    data-type=\"product\"\n    title=\"Ajouter aux favoris\"\n    id=\"wish-44612\">\n    \n  <i class=\"icon add-to-wishlist product\"><\/i>\n\n  <span class=\"sr-only\">\n    Ajouter Pupitre 3 Tiroirs-DGNDS-301S \u00e0 mes favoris  <\/span>\n  <\/button>\n\n      <\/div>\n    <\/div>\n    <div class=\"product__desc__bottom\">\n          <p class=\"product__manufacturer\">44132<\/p>\n        <\/div>\n\n  <\/div>\n<\/a>\n        \n      \n<a href=\"https:\/\/www.foliot.com\/fr\/produits\/dgnds-019s-bureau-vienna\/\" class=\"product__item\" data-product=\"{&quot;types&quot;:&quot;&quot;,&quot;rating&quot;:&quot;-&quot;,&quot;description&quot;:&quot;&quot;,&quot;dimensions&quot;:{&quot;in&quot;:{&quot;depth&quot;:&quot;20&quot;,&quot;height&quot;:&quot;30&quot;,&quot;width&quot;:&quot;36&quot;},&quot;cm&quot;:{&quot;depth&quot;:51,&quot;height&quot;:76,&quot;width&quot;:91}},&quot;image&quot;:&quot;https:\\\/\\\/www.foliot.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/DGNDS-019S_Desk-with-Wooden-round-legs_A.jpg&quot;,&quot;code&quot;:&quot;DGNDS-019S&quot;,&quot;id&quot;:91648}\" >\n  <div class=\"product__image\">\n    <div class=\"product__actions\">\n     <div id=\"compare-actions-DGNDS-019S\" class=\"product__actions__compare\">\n    <\/div>\n    <\/div>\n\n      <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2023\/10\/DGNDS-019S_Desk-with-Wooden-round-legs_A-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>  \n      <div class=\"product__image__hover\">\n    <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.foliot.com\/wp-content\/uploads\/2023\/10\/DGNDS-019S_Desk-with-Wooden-round-legs_C-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>    <\/div>\n    \n\n  <\/div>\n  <div class=\"product__desc\">\n    <div class=\"product__desc__top\">\n      <div class=\"product__desc__top__left\">\n                          <p class=\"product__name\">Bureau Vienna<\/p>\n                          <p class=\"product__code\">DGNDS-019S<\/p>\n              <\/div>\n      <div class=\"product__desc__top__right\">\n                \n  <button class=\"add-to__btn add-to__btn--wishlist add-to-wishlist-btn product\"\n    data-item_id=\"91648\"\n    data-item_name=\"Bureau Vienna\"\n    data-type=\"product\"\n    title=\"Ajouter aux favoris\"\n    id=\"wish-91648\">\n    \n  <i class=\"icon add-to-wishlist product\"><\/i>\n\n  <span class=\"sr-only\">\n    Ajouter DGNDS-019S Bureau Vienna \u00e0 mes favoris  <\/span>\n  <\/button>\n\n      <\/div>\n    <\/div>\n    <div class=\"product__desc__bottom\">\n        <\/div>\n\n  <\/div>\n<\/a>\n   \n\n\n<\/div>   \n\n<div class=\"facetwp-facet facetwp-facet-facetwp_loadmore facetwp-type-pager\" data-name=\"facetwp_loadmore\" data-type=\"pager\"><\/div>\n<div class=\"popup popup--project\">\n  <div class=\"popup__overlay\"><\/div>\n  <div class=\"popup__flex-container\">\n    <div class=\"popup__inner\">\n\n    <\/div>\n  <\/div>\n<\/div>\n\n<script type=\"text\/tmpl\" id=\"tmpl-add-to-project\">\n\n<button id=\"popup-close\"><\/button>\n<div class=\"popup--project__item__image\">\n  <img decoding=\"async\" src=\"{{ data.image }}\" alt=\"\">\n<\/div>\n<h3 class=\"popup--project__title\">Ajouter \u00e0 un projet<\/h3>\n<input type=\"text\" placeholder=\"Rechercher\"\n       class=\"popup--project__search\" id=\"popup-project-search\">\n<div id=\"projects-list\" class=\"popup--project__projects\">\n  \n<\/div>\n<div class=\"popup--project__create\">\n  <button class=\"project__newitem__add\"><span><\/span><span><\/span><\/button>\n  <div class=\"project__newitem__content\">\n    <label class=\"project__newitem__placeholer\" for=\"new-item-{{data.id}}\">\n      Create a project    <\/label>\n    <div class=\"project__newitem__container\">\n      <input id=\"new-item-{{data.id}}\" class=\"project__newitem__title\" type=\"text\" placeholder=\"Enter a name\">\n      <button class=\"project__newitem__save\">Enregistrer<span\n            class=\"sr-only\">[Item name] to [project name]<\/span><\/button>\n    <\/div>\n  <\/div>\n<\/div>\n<\/script>\n\n<script type=\"text\/tmpl\" id=\"tmpl-project-item\">\n<div class=\"project__item\">\n  <div class=\"project__item__inner\">\n    <div class=\"project__item__avatar\"\n         style=\"background-image:url(https:\/\/www.foliot.com\/wp-content\/themes\/foliot.com\/dist\/images\/defaults\/default.jpg)\"><\/div>\n    <p class=\"project__item__name\">{{ data.project_title }}<\/p>\n  <\/div>\n  <button class=\"project__item__save\"\n          data-project-id=\"{{ data.project_id }}\"\n  >\n    Enregistrer    <span class=\"sr-only\">[Item name] to [project name]<\/span\n  <\/button>\n<\/div>\n<\/script>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Modernes ou traditionnels, les pupitres Foliot sont polyvalents et robustes pour assurer leur dur\u00e9e de vie dans un environnement institutionnel et dynamique.<\/p>\n","protected":false},"author":33,"featured_media":80942,"parent":82468,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/pages\/83727"}],"collection":[{"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/comments?post=83727"}],"version-history":[{"count":2,"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/pages\/83727\/revisions"}],"predecessor-version":[{"id":83731,"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/pages\/83727\/revisions\/83731"}],"up":[{"embeddable":true,"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/pages\/82468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/media\/80942"}],"wp:attachment":[{"href":"https:\/\/www.foliot.com\/fr\/wp-json\/wp\/v2\/media?parent=83727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}